{"id":17636,"date":"2026-02-20T18:08:23","date_gmt":"2026-02-20T18:08:23","guid":{"rendered":""},"modified":"2026-02-20T18:08:23","modified_gmt":"2026-02-20T18:08:23","slug":"5150000802401-rondella-piana-zincata-8x24","status":"publish","type":"product","link":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/","title":{"rendered":"RONDELLA PIANA ZINCATA 8&#215;24"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class='disponibilita-personalizzata'>\n<\/div>\n","protected":false},"featured_media":17644,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[560],"product_tag":[],"class_list":["post-17636","product","type-product","status-publish","has-post-thumbnail","product_cat-accessori-di-consumo","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RONDELLA PIANA ZINCATA 8x24 - Generale Elettrica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RONDELLA PIANA ZINCATA 8x24 - Generale Elettrica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/\" \/>\n<meta property=\"og:site_name\" content=\"Generale Elettrica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61557292659283\" \/>\n<meta property=\"og:image\" content=\"https:\/\/generale-elettrica.com\/wp-content\/uploads\/2026\/02\/99199715_5150000802401_4361.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/\",\"url\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/\",\"name\":\"RONDELLA PIANA ZINCATA 8x24 - Generale Elettrica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/generale-elettrica.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/99199715_5150000802401_4361.png\",\"datePublished\":\"2026-02-20T18:08:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/#primaryimage\",\"url\":\"https:\\\/\\\/generale-elettrica.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/99199715_5150000802401_4361.png\",\"contentUrl\":\"https:\\\/\\\/generale-elettrica.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/99199715_5150000802401_4361.png\",\"width\":800,\"height\":800,\"caption\":\"99199715\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/product\\\/5150000802401-rondella-piana-zincata-8x24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/generale-elettrica.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/generale-elettrica.com\\\/index.php\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RONDELLA PIANA ZINCATA 8&#215;24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/#website\",\"url\":\"https:\\\/\\\/generale-elettrica.com\\\/\",\"name\":\"Generale Elettrica | Vendita Online di Materiale Elettrico, Domotica, Videosorveglianza e Termoidraulica\",\"description\":\"Negozio di Elettronica, Videosorveglianza, Antifurto e non solo...\",\"publisher\":{\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/generale-elettrica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/#organization\",\"name\":\"Generale Elettrica SRL\",\"url\":\"https:\\\/\\\/generale-elettrica.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/generale-elettrica.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ge_logo_nero_min.png\",\"contentUrl\":\"https:\\\/\\\/generale-elettrica.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ge_logo_nero_min.png\",\"width\":350,\"height\":109,\"caption\":\"Generale Elettrica SRL\"},\"image\":{\"@id\":\"https:\\\/\\\/generale-elettrica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61557292659283\",\"https:\\\/\\\/www.instagram.com\\\/generale.elettrica\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RONDELLA PIANA ZINCATA 8x24 - Generale Elettrica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/","og_locale":"it_IT","og_type":"article","og_title":"RONDELLA PIANA ZINCATA 8x24 - Generale Elettrica","og_url":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/","og_site_name":"Generale Elettrica","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61557292659283","og_image":[{"width":800,"height":800,"url":"https:\/\/generale-elettrica.com\/wp-content\/uploads\/2026\/02\/99199715_5150000802401_4361.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/","url":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/","name":"RONDELLA PIANA ZINCATA 8x24 - Generale Elettrica","isPartOf":{"@id":"https:\/\/generale-elettrica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/#primaryimage"},"image":{"@id":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/#primaryimage"},"thumbnailUrl":"https:\/\/generale-elettrica.com\/wp-content\/uploads\/2026\/02\/99199715_5150000802401_4361.png","datePublished":"2026-02-20T18:08:23+00:00","breadcrumb":{"@id":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/#primaryimage","url":"https:\/\/generale-elettrica.com\/wp-content\/uploads\/2026\/02\/99199715_5150000802401_4361.png","contentUrl":"https:\/\/generale-elettrica.com\/wp-content\/uploads\/2026\/02\/99199715_5150000802401_4361.png","width":800,"height":800,"caption":"99199715"},{"@type":"BreadcrumbList","@id":"https:\/\/generale-elettrica.com\/index.php\/product\/5150000802401-rondella-piana-zincata-8x24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/generale-elettrica.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/generale-elettrica.com\/index.php\/negozio\/"},{"@type":"ListItem","position":3,"name":"RONDELLA PIANA ZINCATA 8&#215;24"}]},{"@type":"WebSite","@id":"https:\/\/generale-elettrica.com\/#website","url":"https:\/\/generale-elettrica.com\/","name":"Generale Elettrica | Vendita Online di Materiale Elettrico, Domotica, Videosorveglianza e Termoidraulica","description":"Negozio di Elettronica, Videosorveglianza, Antifurto e non solo...","publisher":{"@id":"https:\/\/generale-elettrica.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/generale-elettrica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/generale-elettrica.com\/#organization","name":"Generale Elettrica SRL","url":"https:\/\/generale-elettrica.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/generale-elettrica.com\/#\/schema\/logo\/image\/","url":"https:\/\/generale-elettrica.com\/wp-content\/uploads\/2024\/05\/ge_logo_nero_min.png","contentUrl":"https:\/\/generale-elettrica.com\/wp-content\/uploads\/2024\/05\/ge_logo_nero_min.png","width":350,"height":109,"caption":"Generale Elettrica SRL"},"image":{"@id":"https:\/\/generale-elettrica.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61557292659283","https:\/\/www.instagram.com\/generale.elettrica"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/product\/17636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/product\/17636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/media\/17644"}],"wp:attachment":[{"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/media?parent=17636"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=17636"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=17636"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/generale-elettrica.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=17636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}